{"id":1041,"count":2,"description":"Als junger Mann lernte er das Goldschmiede Handwerk bei Jensen in Kopenhagen. Danach zog es ihn in die weite Welt. Im Jahre 1988 er\u00f6ffnete der begabte Gold- und Silberschmied sein erstes Atelier. Seine langj\u00e4hrige Karriere brachte ihm viel Ruhm und einen Platz im Museum of Modern Art in New York.","link":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/tag\/flemming-bo-hansen\/","name":"Flemming Bo Hansen","slug":"flemming-bo-hansen","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Als junger Mann lernte er das Goldschmiede Handwerk bei Jensen in Kopenhagen. Danach zog es ihn in die weite Welt. Im Jahre 1988 er\u00f6ffnete der begabte Gold- und Silberschmied sein erstes Atelier. Seine langj\u00e4hrige Karriere brachte ihm viel Ruhm und einen Platz im Museum of Modern Art in New York.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.uhren-shop.ch\/uhren-magazin\/tag\/flemming-bo-hansen\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Schweizer Uhren Magazin \u231a Uhrenblog &amp; Ratgeber - News &amp; Tipps\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Flemming Bo Hansen \u231a Schweizer Uhren Magazin\" \/>\n\t\t<meta property=\"og:description\" content=\"Als junger Mann lernte er das Goldschmiede Handwerk bei Jensen in Kopenhagen. Danach zog es ihn in die weite Welt. Im Jahre 1988 er\u00f6ffnete der begabte Gold- und Silberschmied sein erstes Atelier. Seine langj\u00e4hrige Karriere brachte ihm viel Ruhm und einen Platz im Museum of Modern Art in New York.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.uhren-shop.ch\/uhren-magazin\/tag\/flemming-bo-hansen\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.uhren-shop.ch\/uhren-magazin\/wp-content\/uploads\/2020\/03\/Banner-Flemming-Bo-Hansen-2007.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.uhren-shop.ch\/uhren-magazin\/wp-content\/uploads\/2020\/03\/Banner-Flemming-Bo-Hansen-2007.jpg\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UHRENshop\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@UHRENshopCH\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Flemming Bo Hansen \u231a Schweizer Uhren Magazin\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Als junger Mann lernte er das Goldschmiede Handwerk bei Jensen in Kopenhagen. Danach zog es ihn in die weite Welt. Im Jahre 1988 er\u00f6ffnete der begabte Gold- und Silberschmied sein erstes Atelier. Seine langj\u00e4hrige Karriere brachte ihm viel Ruhm und einen Platz im Museum of Modern Art in New York.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.uhren-shop.ch\/uhren-magazin\/wp-content\/uploads\/2020\/03\/Banner-Flemming-Bo-Hansen-2007.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uhren-shop.ch\\\/uhren-magazin\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/1041\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.uhren-shop.ch\\\/uhren-magazin#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.uhren-shop.ch\\\/uhren-magazin\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.uhren-shop.ch\\\/uhren-magazin\\\/tag\\\/flemming-bo-hansen\\\/#listItem\",\"name\":\"Flemming Bo Hansen\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.uhren-shop.ch\\\/uhren-magazin\\\/tag\\\/flemming-bo-hansen\\\/#listItem\",\"position\":2,\"name\":\"Flemming Bo Hansen\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.uhren-shop.ch\\\/uhren-magazin#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.uhren-shop.ch\\\/uhren-magazin\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/1041\\\/#collectionpage\",\"url\":\"https:\\\/\\\/www.uhren-shop.ch\\\/uhren-magazin\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/1041\\\/\",\"name\":\"Flemming Bo Hansen \\u231a Schweizer Uhren Magazin\",\"description\":\"Als junger Mann lernte er das Goldschmiede Handwerk bei Jensen in Kopenhagen. Danach zog es ihn in die weite Welt. Im Jahre 1988 er\\u00f6ffnete der begabte Gold- und Silberschmied sein erstes Atelier. Seine langj\\u00e4hrige Karriere brachte ihm viel Ruhm und einen Platz im Museum of Modern Art in New York.\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uhren-shop.ch\\\/uhren-magazin\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uhren-shop.ch\\\/uhren-magazin\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/1041\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.uhren-shop.ch\\\/uhren-magazin\\\/#organization\",\"name\":\"Online Magazin von UHREN-shop Schweiz\",\"description\":\"Das Schweizer Uhren Magazin - Uhrenblog - Ratgeber, News &amp; Tipps\",\"url\":\"https:\\\/\\\/www.uhren-shop.ch\\\/uhren-magazin\\\/\",\"email\":\"info@uhren-shop.ch\",\"telephone\":\"+41612639208\",\"foundingDate\":\"1967-01-01\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.uhren-shop.ch\\\/uhren-magazin\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cropped-Logo-Schweizer-Uhren-Shop-Magazin-4.png\",\"@id\":\"https:\\\/\\\/www.uhren-shop.ch\\\/uhren-magazin\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/1041\\\/#organizationLogo\",\"width\":600,\"height\":200},\"image\":{\"@id\":\"https:\\\/\\\/www.uhren-shop.ch\\\/uhren-magazin\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/1041\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UHRENshop\",\"https:\\\/\\\/twitter.com\\\/UHRENshopCH\",\"https:\\\/\\\/www.instagram.com\\\/uhrenbasel\\\/\",\"https:\\\/\\\/www.pinterest.de\\\/uhrenschweiz\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/UhrenshopChOriginal\",\"https:\\\/\\\/ch.linkedin.com\\\/company\\\/uhren-shop-ch\",\"https:\\\/\\\/uhren-basel.tumblr.com\",\"https:\\\/\\\/www.yelp.com\\\/biz\\\/uhren-shop-ch-basel-2\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Au_Bijou\"],\"address\":{\"@id\":\"https:\\\/\\\/www.uhren-shop.ch\\\/uhren-magazin\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"R\\u00fcdengasse 3-1\",\"postalCode\":\"4001\",\"addressLocality\":\"Basel\",\"addressRegion\":\"BS\",\"addressCountry\":\"CH\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uhren-shop.ch\\\/uhren-magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.uhren-shop.ch\\\/uhren-magazin\\\/\",\"name\":\"Schweizer Uhren Magazin \\u231a Blog de montres\",\"description\":\"Uhrenblog & Ratgeber - News & Tipps\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.uhren-shop.ch\\\/uhren-magazin\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Flemming Bo Hansen \u231a Schweizer Uhren Magazin<\/title>\n\n","aioseo_head_json":{"title":"Flemming Bo Hansen \u231a Schweizer Uhren Magazin","description":"Als junger Mann lernte er das Goldschmiede Handwerk bei Jensen in Kopenhagen. Danach zog es ihn in die weite Welt. Im Jahre 1988 er\u00f6ffnete der begabte Gold- und Silberschmied sein erstes Atelier. Seine langj\u00e4hrige Karriere brachte ihm viel Ruhm und einen Platz im Museum of Modern Art in New York.","canonical_url":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/tag\/flemming-bo-hansen\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/wp-json\/wp\/v2\/tags\/1041\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.uhren-shop.ch\/uhren-magazin#listItem","position":1,"name":"Home","item":"https:\/\/www.uhren-shop.ch\/uhren-magazin","nextItem":{"@type":"ListItem","@id":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/tag\/flemming-bo-hansen\/#listItem","name":"Flemming Bo Hansen"}},{"@type":"ListItem","@id":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/tag\/flemming-bo-hansen\/#listItem","position":2,"name":"Flemming Bo Hansen","previousItem":{"@type":"ListItem","@id":"https:\/\/www.uhren-shop.ch\/uhren-magazin#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/wp-json\/wp\/v2\/tags\/1041\/#collectionpage","url":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/wp-json\/wp\/v2\/tags\/1041\/","name":"Flemming Bo Hansen \u231a Schweizer Uhren Magazin","description":"Als junger Mann lernte er das Goldschmiede Handwerk bei Jensen in Kopenhagen. Danach zog es ihn in die weite Welt. Im Jahre 1988 er\u00f6ffnete der begabte Gold- und Silberschmied sein erstes Atelier. Seine langj\u00e4hrige Karriere brachte ihm viel Ruhm und einen Platz im Museum of Modern Art in New York.","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/#website"},"breadcrumb":{"@id":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/wp-json\/wp\/v2\/tags\/1041\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/#organization","name":"Online Magazin von UHREN-shop Schweiz","description":"Das Schweizer Uhren Magazin - Uhrenblog - Ratgeber, News &amp; Tipps","url":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/","email":"info@uhren-shop.ch","telephone":"+41612639208","foundingDate":"1967-01-01","logo":{"@type":"ImageObject","url":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/wp-content\/uploads\/2025\/11\/cropped-Logo-Schweizer-Uhren-Shop-Magazin-4.png","@id":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/wp-json\/wp\/v2\/tags\/1041\/#organizationLogo","width":600,"height":200},"image":{"@id":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/wp-json\/wp\/v2\/tags\/1041\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/UHRENshop","https:\/\/twitter.com\/UHRENshopCH","https:\/\/www.instagram.com\/uhrenbasel\/","https:\/\/www.pinterest.de\/uhrenschweiz\/","https:\/\/www.youtube.com\/c\/UhrenshopChOriginal","https:\/\/ch.linkedin.com\/company\/uhren-shop-ch","https:\/\/uhren-basel.tumblr.com","https:\/\/www.yelp.com\/biz\/uhren-shop-ch-basel-2","https:\/\/en.wikipedia.org\/wiki\/Au_Bijou"],"address":{"@id":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/#postaladdress","@type":"PostalAddress","streetAddress":"R\u00fcdengasse 3-1","postalCode":"4001","addressLocality":"Basel","addressRegion":"BS","addressCountry":"CH"}},{"@type":"WebSite","@id":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/#website","url":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/","name":"Schweizer Uhren Magazin \u231a Blog de montres","description":"Uhrenblog & Ratgeber - News & Tipps","inLanguage":"de-DE","publisher":{"@id":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Schweizer Uhren Magazin \u231a Uhrenblog &amp; Ratgeber - News &amp; Tipps","og:type":"article","og:title":"Flemming Bo Hansen \u231a Schweizer Uhren Magazin","og:description":"Als junger Mann lernte er das Goldschmiede Handwerk bei Jensen in Kopenhagen. Danach zog es ihn in die weite Welt. Im Jahre 1988 er\u00f6ffnete der begabte Gold- und Silberschmied sein erstes Atelier. Seine langj\u00e4hrige Karriere brachte ihm viel Ruhm und einen Platz im Museum of Modern Art in New York.","og:url":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/tag\/flemming-bo-hansen\/","og:image":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/wp-content\/uploads\/2020\/03\/Banner-Flemming-Bo-Hansen-2007.jpg","og:image:secure_url":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/wp-content\/uploads\/2020\/03\/Banner-Flemming-Bo-Hansen-2007.jpg","article:publisher":"https:\/\/www.facebook.com\/UHRENshop","twitter:card":"summary","twitter:site":"@UHRENshopCH","twitter:title":"Flemming Bo Hansen \u231a Schweizer Uhren Magazin","twitter:description":"Als junger Mann lernte er das Goldschmiede Handwerk bei Jensen in Kopenhagen. Danach zog es ihn in die weite Welt. Im Jahre 1988 er\u00f6ffnete der begabte Gold- und Silberschmied sein erstes Atelier. Seine langj\u00e4hrige Karriere brachte ihm viel Ruhm und einen Platz im Museum of Modern Art in New York.","twitter:image":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/wp-content\/uploads\/2020\/03\/Banner-Flemming-Bo-Hansen-2007.jpg"},"aioseo_meta_data":{"term_id":"1041","title":null,"description":null,"keywords":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"custom_image","og_image_custom_url":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/wp-content\/uploads\/2020\/03\/Banner-Flemming-Bo-Hansen-2007.jpg","og_image_custom_fields":null,"og_custom_image_width":null,"og_custom_image_height":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"pillar_content":null,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","tabs":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-13 12:13:58","breadcrumb_settings":null,"created":"2025-06-23 13:54:38","updated":"2026-05-13 12:13:58","og_image_url":null,"og_image_width":null,"og_image_height":null,"twitter_image_url":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.uhren-shop.ch\/uhren-magazin\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tFlemming Bo Hansen\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.uhren-shop.ch\/uhren-magazin"},{"label":"Flemming Bo Hansen","link":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/tag\/flemming-bo-hansen\/"}],"_links":{"self":[{"href":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/wp-json\/wp\/v2\/tags\/1041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.uhren-shop.ch\/uhren-magazin\/wp-json\/wp\/v2\/posts?tags=1041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}